{"id":7299,"date":"2026-07-01T12:44:07","date_gmt":"2026-07-01T12:44:07","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=7299"},"modified":"2026-07-01T12:48:00","modified_gmt":"2026-07-01T12:48:00","slug":"allegorie-con-putti-2","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/allegorie-con-putti-2\/","title":{"rendered":"Allegorie con putti"},"content":{"rendered":"<div id=\"gutenslider-ib9dnsl4p\" class=\"wp-block-eedee-block-gutenslider gs-frontend content-change alignnone adaptive-height arrow-style-1 arrow-position-sides arrow-mb-none arrows-lg arrows-md arrows-sm dot-style-1 dots-lg dots-md dots-sm dot-position-bottom is-position-center-center mb-none wrap-auto-height\" data-parallax-direction=\"down\" data-parallax-amount=\"1.3\" data-lg-transition=\"lg-slide\" data-hash=\"\" ><div class=\"eedee-swiper-outer\" style=\"--gutenslider-min-height: 50vh;--gutenslider-arrow-size: 30px;--gutenslider-dot-size: 25px;--gutenslider-arrow-color: #ffffff;--gutenslider-dot-color: #ffffff;--gutenslider-padding-y-mobile: 40px;--gutenslider-padding-x-mobile: 40px;--gutenslider-padding-y-tablet: 40px;--gutenslider-padding-x-tablet: 40px;--gutenslider-padding-y-desktop: 40px;--gutenslider-padding-x-desktop: 40px;--gutenslider-bg-image: url();--gutenslider-min-height-md: 50vh;--gutenslider-min-height-sm: 50vh;--gutenslider-padding-x: 40px;--gutenslider-padding-x-md: 40px;--gutenslider-padding-x-sm: 20px;--gutenslider-padding-y: 40px;--gutenslider-padding-y-md: 40px;--gutenslider-padding-y-sm: 20px;--gutenslider-arrow-size-md: 30px;--gutenslider-arrow-size-sm: 30px;--gutenslider-dot-size-md: 25px;--gutenslider-dot-size-sm: 25px;--gutenslider-arrow-bg-color: transparent;--gutenslider-arrow-hover-color: #eeeeee;--gutenslider-arrow-bg-hover-color: transparent;--gutenslider-arrow-x-offset: 10px;--gutenslider-arrow-x-offset-md: 10px;--gutenslider-arrow-x-offset-sm: 10px;--gutenslider-arrow-y-offset: 0px;--gutenslider-arrow-y-offset-md: 0px;--gutenslider-arrow-y-offset-sm: 0px;--gutenslider-arrow-x-spacing: 0px;--gutenslider-dot-y-offset: 10px;--gutenslider-dot-y-offset-md: 10px;--gutenslider-dot-y-offset-sm: 10px;--gutenslider-margin-x: 0px;--gutenslider-margin-x-md: 0px;--gutenslider-margin-x-sm: 0px;--gutenslider-margin-y: 0px;--gutenslider-margin-y-md: 0px;--gutenslider-margin-y-sm: 0px;--gutenslider-divider-top: 60px;--gutenslider-divider-bottom: 60px;--gutenslider-lightgallery-bg: #ffffff;--gutenslider-lightgallery-font: #000000;--gs-first-pos: 50% 50%;--gs-gap-vertical: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );--gs-gap-horizontal: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );\"><div class=\"gutenslider-divider-top\" style=\"color:#fff;\"><\/div><div class=\"swiper\" data-settings='{\"autoplay\":{\"delay\":3000,\"pauseOnMouseEnter\":true,\"disableOnInteraction\":false},\"speed\":700,\"direction\":\"horizontal\",\"autoHeight\":\"\",\"loop\":true,\"centeredSlides\":true,\"spaceBetween\":0,\"slidesPerView\":1,\"slidesPerGroup\":1,\"effect\":\"slide\",\"coverflowEffect\":{\"rotate\":30,\"slideShadows\":false,\"depth\":100,\"stretch\":50,\"modifier\":1},\"fadeEffect\":{\"crossFade\":true},\"zoom\":\"\",\"navigation\":{\"nextEl\":\"#gutenslider-ib9dnsl4p .eedee-gutenslider-next\",\"prevEl\":\"#gutenslider-ib9dnsl4p .eedee-gutenslider-prev\"},\"pagination\":{\"type\":\"bullets\",\"clickable\":true,\"dynamicBullets\":false,\"el\":\"#gutenslider-ib9dnsl4p .eedee-gutenslider-pagination\"},\"pauseOnHover\":\"1\",\"watchSlidesProgress\":true,\"watchSlidesVisibility\":true,\"settingsMd\":{\"autoHeight\":\"\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"settingsLg\":{\"autoHeight\":\"1\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"hasLg\":false,\"hasLgCounter\":true,\"isFullScreen\":false,\"arrowsFollowMouse\":false,\"lgTitle\":\"none\",\"lgCaption\":\"none\",\"lgThumbnails\":true,\"lgZoomEnabled\":false,\"keyboard\":{\"keyboard\":{\"enabled\":true,\"onlyInViewport\":true}},\"hashNavigation\":false,\"dividers\":false}'><div class=\"swiper-wrapper\">\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:209;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"712\" height=\"1024\" class=\"wp-image-7305\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-712x1024.jpg\" alt=\"Fedele Fischetti\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"d492b\" data-title=\"Allegorie con putti\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-712x1024.jpg 712w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-209x300.jpg 209w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-768x1104.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-50x72.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-1600x2300.jpg 1600w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-1068x1536.jpg 1068w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-1424x2048.jpg 1424w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-52x75.jpg 52w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-668x960.jpg 668w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-334x480.jpg 334w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-480x690.jpg 480w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-9-1-scaled.jpg 1781w\" sizes=\"(max-width:767px) 480px, 712px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:238;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"811\" height=\"1024\" class=\"wp-image-7307\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-811x1024.jpg\" alt=\"Fedele Fischetti\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"d492b (con cornice)\" data-title=\"Allegorie con putti\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-811x1024.jpg 811w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-238x300.jpg 238w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-768x970.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-50x63.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-1600x2020.jpg 1600w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-1217x1536.jpg 1217w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-1622x2048.jpg 1622w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-59x75.jpg 59w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-760x960.jpg 760w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-380x480.jpg 380w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-480x606.jpg 480w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-10-1-scaled.jpg 2028w\" sizes=\"(max-width:767px) 480px, (max-width:811px) 100vw, 811px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n<\/div><\/div><button class=\"eedee-gutenslider-nav eedee-gutenslider-prev\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"13\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M10.828 12l4.95 4.95-1.414 1.414L8 12l6.364-6.364 1.414 1.414z\"\/><\/svg><\/button><button class=\"eedee-gutenslider-nav eedee-gutenslider-next\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"11\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M13.172 12l-4.95-4.95 1.414-1.414L16 12l-6.364 6.364-1.414-1.414z\"\/><\/svg><\/button><div class=\"eedee-gutenslider-pagination\"><\/div><div class=\"gutenslider-divider-bottom \" style=\"color:#fff;\"><\/div><\/div><\/div>\n\n\n<p class=\"has-text-align-center\">FEDELE FISCHETTI<\/p>\n\n\n\n<p class=\"has-text-align-center\">Napoli, 1732 &#8211; 1792<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Allegorie con putti<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">Data: terzo quarto del XVIII secolo<\/p>\n\n\n\n<p class=\"has-text-align-center\">olio su tavola, cm. 23&#215;31<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il ciclo pittorico in esame, composto da quattro delicate tavolette di area meridionale databili al pieno XVIII secolo, rappresenta un esempio emblematico di decorazione d\u2019arredo di alta qualit\u00e0, oggi attribuito alla mano del pittore tardo barocco partenopeo Fedele Fischetti. L\u2019ipotesi pi\u00f9 accreditata \u00e8 che questi elementi lignei facessero parte della struttura di un mobile di pregio o di una boiserie, con buona probabilit\u00e0 uno stipo, una portantina o una carrozza, come sembra suggerire il fondo oro, caratteristica riscontrabile a Napoli in dipinti coevi con simile destinazione dello stesso Fischetti, che mostrano spiccate qualit\u00e0 decorative.<\/p>\n\n\n\n<p>La narrazione figurativa si snoda attraverso un raffinato gioco di allegorie, in cui i putti diventano veicolo di profondi concetti morali e filosofici, secondo una cifra stilistica che trova puntuali riscontri nella produzione autografa del pittore. In questo palinsesto decorativo, la prima tavola, verosimilmente dedicata alla Sapienza o alla Matematica, coglie il putto nell\u2019atto di consultare un volume aperto accanto a una squadra, esaltando la conoscenza razionale che ordina il mondo. Segue la possibile allegoria del Potere e della Prosperit\u00e0, dove la figura infantile si protende verso un trono accompagnata da una cornucopia ricolma di frutti, simbolo dell\u2019abbondanza derivante da un\u2019autorit\u00e0 illuminata.<\/p>\n\n\n\n<p>Particolarmente significativa appare la tavoletta della Fortuna, interpretata attraverso la <em>Rota Fortunae<\/em>: qui il movimento della ruota determina il destino delle figure, con un putto trionfante sulla sommit\u00e0 e un altro al suolo in un pianto disperato, monito sulla mutevolezza della sorte. Il ciclo si chiude con la possibile immagine dell\u2019Architettura, identificabile dalle grandi tavole centinate sostenute dai piccoli protagonisti. I piccoli pannelli riflettono dunque la cultura tardo-barocca meridionale, unendo la morbidezza della pennellata a una funzione didascalica tipica delle grandi dimore nobiliari del Settecento.<\/p>\n\n\n\n<p>La carriera di Fedele Fischetti si sviluppa nel solco di Solimena, con evidenti richiami anche all\u2019arte dei concittadini De Matteis e De Mura, mostrando tuttavia un crescente interesse per il classicismo di Batoni. Tali interessi emergono gi\u00e0 nelle opere pi\u00f9 antiche datate, risalenti al sesto decennio del secolo, che mostrano le affinit\u00e0 pi\u00f9 strette con le opere in esame; successivamente, la sua arte tende progressivamente verso un gusto di impronta neoclassica, come testimoniano, ad esempio, le tele per il Palacio Real di Madrid, pi\u00f9 vicine alle novit\u00e0 introdotte in citt\u00e0 da Anton Raphael Mengs e da Angelica Kauffmann.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-tornabuoni-arte wp-block-embed-tornabuoni-arte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"TKPS6roBnS\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/allegorie-con-putti\/\">Allegorie con putti<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Allegorie con putti&#8221; &#8212; Tornabuoni Arte\" src=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/allegorie-con-putti\/embed\/#?secret=7vrQSVOzs0#?secret=TKPS6roBnS\" data-secret=\"TKPS6roBnS\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-tornabuoni-arte wp-block-embed-tornabuoni-arte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"1peutDt4Ir\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/allegorie-con-putti-3\/\">Allegorie con putti<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Allegorie con putti&#8221; &#8212; Tornabuoni Arte\" src=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/allegorie-con-putti-3\/embed\/#?secret=SyPJbDHhRj#?secret=1peutDt4Ir\" data-secret=\"1peutDt4Ir\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-tornabuoni-arte wp-block-embed-tornabuoni-arte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Ne8dcMMhYl\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/allegorie-con-putti-4\/\">Allegorie con putti<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Allegorie con putti&#8221; &#8212; Tornabuoni Arte\" src=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/allegorie-con-putti-4\/embed\/#?secret=YMJxVW96fP#?secret=Ne8dcMMhYl\" data-secret=\"Ne8dcMMhYl\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":7305,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-types":[17],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/7299"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=7299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/7305"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=7299"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=7299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}