{"id":6862,"date":"2025-12-02T14:43:56","date_gmt":"2025-12-02T14:43:56","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=6862"},"modified":"2026-05-06T14:44:44","modified_gmt":"2026-05-06T14:44:44","slug":"leducazione-della-vergine","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/leducazione-della-vergine\/","title":{"rendered":"L&#8217;educazione della Vergine"},"content":{"rendered":"<div id=\"gutenslider-ftbmcnfjo\" class=\"wp-block-eedee-block-gutenslider gs-frontend content-change alignnone adaptive-height arrow-style-1 arrow-position-sides arrow-mb-none arrows-lg arrows-md arrows-sm dot-style-1 dots-lg dots-md dots-sm dot-position-bottom is-position-center-center mb-none wrap-auto-height\" data-parallax-direction=\"down\" data-parallax-amount=\"1.3\" data-lg-transition=\"lg-slide\" data-hash=\"\" ><div class=\"eedee-swiper-outer\" style=\"--gutenslider-min-height: 50vh;--gutenslider-arrow-size: 30px;--gutenslider-dot-size: 25px;--gutenslider-arrow-color: #ffffff;--gutenslider-dot-color: #ffffff;--gutenslider-padding-y-mobile: 40px;--gutenslider-padding-x-mobile: 40px;--gutenslider-padding-y-tablet: 40px;--gutenslider-padding-x-tablet: 40px;--gutenslider-padding-y-desktop: 40px;--gutenslider-padding-x-desktop: 40px;--gutenslider-bg-image: url();--gutenslider-min-height-md: 50vh;--gutenslider-min-height-sm: 50vh;--gutenslider-padding-x: 40px;--gutenslider-padding-x-md: 40px;--gutenslider-padding-x-sm: 20px;--gutenslider-padding-y: 40px;--gutenslider-padding-y-md: 40px;--gutenslider-padding-y-sm: 20px;--gutenslider-arrow-size-md: 30px;--gutenslider-arrow-size-sm: 30px;--gutenslider-dot-size-md: 25px;--gutenslider-dot-size-sm: 25px;--gutenslider-arrow-bg-color: transparent;--gutenslider-arrow-hover-color: #eeeeee;--gutenslider-arrow-bg-hover-color: transparent;--gutenslider-arrow-x-offset: 10px;--gutenslider-arrow-x-offset-md: 10px;--gutenslider-arrow-x-offset-sm: 10px;--gutenslider-arrow-y-offset: 0px;--gutenslider-arrow-y-offset-md: 0px;--gutenslider-arrow-y-offset-sm: 0px;--gutenslider-arrow-x-spacing: 0px;--gutenslider-dot-y-offset: 10px;--gutenslider-dot-y-offset-md: 10px;--gutenslider-dot-y-offset-sm: 10px;--gutenslider-margin-x: 0px;--gutenslider-margin-x-md: 0px;--gutenslider-margin-x-sm: 0px;--gutenslider-margin-y: 0px;--gutenslider-margin-y-md: 0px;--gutenslider-margin-y-sm: 0px;--gutenslider-divider-top: 60px;--gutenslider-divider-bottom: 60px;--gutenslider-lightgallery-bg: #ffffff;--gutenslider-lightgallery-font: #000000;--gs-first-pos: 50% 50%;--gs-gap-vertical: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );--gs-gap-horizontal: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );\"><div class=\"gutenslider-divider-top\" style=\"color:#fff;\"><\/div><div class=\"swiper\" data-settings='{\"autoplay\":{\"delay\":3000,\"pauseOnMouseEnter\":true,\"disableOnInteraction\":false},\"speed\":700,\"direction\":\"horizontal\",\"autoHeight\":\"\",\"loop\":true,\"centeredSlides\":true,\"spaceBetween\":0,\"slidesPerView\":1,\"slidesPerGroup\":1,\"effect\":\"slide\",\"coverflowEffect\":{\"rotate\":30,\"slideShadows\":false,\"depth\":100,\"stretch\":50,\"modifier\":1},\"fadeEffect\":{\"crossFade\":true},\"zoom\":\"\",\"navigation\":{\"nextEl\":\"#gutenslider-ftbmcnfjo .eedee-gutenslider-next\",\"prevEl\":\"#gutenslider-ftbmcnfjo .eedee-gutenslider-prev\"},\"pagination\":{\"type\":\"bullets\",\"clickable\":true,\"dynamicBullets\":false,\"el\":\"#gutenslider-ftbmcnfjo .eedee-gutenslider-pagination\"},\"pauseOnHover\":\"1\",\"watchSlidesProgress\":true,\"watchSlidesVisibility\":true,\"settingsMd\":{\"autoHeight\":\"\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"settingsLg\":{\"autoHeight\":\"1\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"hasLg\":false,\"hasLgCounter\":true,\"isFullScreen\":false,\"arrowsFollowMouse\":false,\"lgTitle\":\"none\",\"lgCaption\":\"none\",\"lgThumbnails\":true,\"lgZoomEnabled\":false,\"keyboard\":{\"keyboard\":{\"enabled\":true,\"onlyInViewport\":true}},\"hashNavigation\":false,\"dividers\":false}'><div class=\"swiper-wrapper\">\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:295;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"1024\" height=\"1007\" class=\"wp-image-6861\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-1024x1007.jpg\" alt=\"Francesco Trevisani \n(Capodistria, 1656 - Roma, 1746)\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"d455\" data-title=\"L&#039;educazione della vergine\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-1024x1007.jpg 1024w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-300x295.jpg 300w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-768x755.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-50x49.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-1600x1574.jpg 1600w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-1536x1511.jpg 1536w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-76x75.jpg 76w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-960x944.jpg 960w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-488x480.jpg 488w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-480x472.jpg 480w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455.jpg 1705w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:295;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"1024\" height=\"1006\" class=\"wp-image-6859\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-1024x1006.jpg\" alt=\"Francesco Trevisani \n(Capodistria, 1656 - Roma, 1746)\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"d455 (con cornice)\" data-title=\"L&#039;educazione della vergine\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-1024x1006.jpg 1024w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-300x295.jpg 300w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-768x755.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-50x49.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-1600x1572.jpg 1600w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-1536x1509.jpg 1536w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-2048x2012.jpg 2048w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-76x75.jpg 76w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-960x943.jpg 960w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-489x480.jpg 489w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d455-con-cornice-480x472.jpg 480w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n<\/div><\/div><button class=\"eedee-gutenslider-nav eedee-gutenslider-prev\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"13\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M10.828 12l4.95 4.95-1.414 1.414L8 12l6.364-6.364 1.414 1.414z\"\/><\/svg><\/button><button class=\"eedee-gutenslider-nav eedee-gutenslider-next\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"11\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M13.172 12l-4.95-4.95 1.414-1.414L16 12l-6.364 6.364-1.414-1.414z\"\/><\/svg><\/button><div class=\"eedee-gutenslider-pagination\"><\/div><div class=\"gutenslider-divider-bottom \" style=\"color:#fff;\"><\/div><\/div><\/div>\n\n\n<p class=\"has-text-align-center\">FRANCESCO TREVISANI<\/p>\n\n\n\n<p class=\"has-text-align-center\">(Capodistria, 1656 &#8211; Roma, 1746)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>L&#8217;educazione della Vergine<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">olio su tela, cm. 129 diametro<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Databile intorno all&#8217;ultimo decennio del XVII secolo, il dipinto \u00e8 stato recentemente attribuito al pittore tardo-barocco Francesco Trevisani, negli anni immediatamente successivi al suo trasferimento a Roma. Il pittore istriano parte dalla tradizione dei \u201ctenebrosi\u201d e scandisce le sue composizioni con l\u2019uso accentuato del chiaroscuro, per poi virare verso un classicismo pi\u00f9 forte in et\u00e0 matura. Trevisani infatti si trasferisce a Roma dove entra nel giro dei pittori di Papa Albani, Clemente XI, che spinse verso una pittura devota e piana, inondata di luce. Il dipinto raffigura l&#8217;episodio religioso dell&#8217;Educazione della Vergine, tratto dalle fonti apocrife dell&#8217;infanzia di Maria. L&#8217;opera di Trevisani mostra una Sant\u2019Anna, dagli accentuati tratti senili, nell&#8217;atto di educare la figlia, iniziandola alla lettura e allo studio. Sulla sinistra troviamo un Gioacchino dallo sguardo assorto, mentre in alto due cherubini assistono alla scena.<\/p>\n\n\n\n<p>Di origini istriane, Francesco Trevisani si form\u00f2 a Venezia: dapprima nella bottega di Antonio Zanchi, da cui eredit\u00f2 il gusto per composizioni movimentate e l&#8217;uso drammatico del chiaroscuro, e in seguito con Joseph Heintz il Giovane. Da quest&#8217;ultimo, come ricorda il biografo Lione Pascoli, Trevisani \u00abapprese il disegno, il colorito ed il nobil, vago e morbido suo impasto\u00bb, sviluppando inoltre una chiara predilezione per la pittura &#8220;di genere&#8221;. Il successivo trasferimento a Roma, se da una parte consegner\u00e0 all\u2019artista una certa fama, al contempo lo porter\u00e0 ad abbandonare progressivamente l\u2019iniziale matrice stilistica veneziana, a favore di un gusto rococ\u00f2 composto e raffinato.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":6861,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-types":[17],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/6862"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=6862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/6861"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=6862"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=6862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}