{"id":5213,"date":"2023-11-22T14:32:03","date_gmt":"2023-11-22T14:32:03","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=5213"},"modified":"2023-11-23T13:52:45","modified_gmt":"2023-11-23T13:52:45","slug":"paesaggio-con-la-preghiera-del-beato-isidoro-agricola","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-con-la-preghiera-del-beato-isidoro-agricola\/","title":{"rendered":"Paesaggio con la preghiera del Beato Isidoro Agricola"},"content":{"rendered":"<div id=\"gutenslider-cxx39g3gr\" class=\"wp-block-eedee-block-gutenslider gs-frontend content-change alignnone adaptive-height arrow-style-1 arrow-position-sides arrow-mb-none arrows-lg arrows-md arrows-sm dot-style-1 dots-lg dots-md dots-sm dot-position-bottom is-position-center-center mb-none lg-zoom-icon wrap-auto-height\" data-parallax-direction=\"down\" data-parallax-amount=\"1.3\" data-lg-transition=\"lg-slide\" data-hash=\"\" ><div class=\"eedee-swiper-outer\" style=\"--gutenslider-min-height: 50vh;--gutenslider-arrow-size: 30px;--gutenslider-dot-size: 25px;--gutenslider-arrow-color: #ffffff;--gutenslider-dot-color: #ffffff;--gutenslider-padding-y-mobile: 40px;--gutenslider-padding-x-mobile: 40px;--gutenslider-padding-y-tablet: 40px;--gutenslider-padding-x-tablet: 40px;--gutenslider-padding-y-desktop: 40px;--gutenslider-padding-x-desktop: 40px;--gutenslider-bg-image: url();--gutenslider-min-height-md: 50vh;--gutenslider-min-height-sm: 50vh;--gutenslider-padding-x: 40px;--gutenslider-padding-x-md: 40px;--gutenslider-padding-x-sm: 20px;--gutenslider-padding-y: 40px;--gutenslider-padding-y-md: 40px;--gutenslider-padding-y-sm: 20px;--gutenslider-arrow-size-md: 30px;--gutenslider-arrow-size-sm: 30px;--gutenslider-dot-size-md: 25px;--gutenslider-dot-size-sm: 25px;--gutenslider-arrow-bg-color: transparent;--gutenslider-arrow-hover-color: #eeeeee;--gutenslider-arrow-bg-hover-color: transparent;--gutenslider-arrow-x-offset: 10px;--gutenslider-arrow-x-offset-md: 10px;--gutenslider-arrow-x-offset-sm: 10px;--gutenslider-arrow-y-offset: 0px;--gutenslider-arrow-y-offset-md: 0px;--gutenslider-arrow-y-offset-sm: 0px;--gutenslider-arrow-x-spacing: 0px;--gutenslider-dot-y-offset: 10px;--gutenslider-dot-y-offset-md: 10px;--gutenslider-dot-y-offset-sm: 10px;--gutenslider-margin-x: 0px;--gutenslider-margin-x-md: 0px;--gutenslider-margin-x-sm: 0px;--gutenslider-margin-y: 0px;--gutenslider-margin-y-md: 0px;--gutenslider-margin-y-sm: 0px;--gutenslider-divider-top: 60px;--gutenslider-divider-bottom: 60px;--gutenslider-lightgallery-bg: #ffffff;--gutenslider-lightgallery-font: #000000;--gs-first-pos: 50% 50%;--gs-gap-vertical: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );--gs-gap-horizontal: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );\"><div class=\"gutenslider-divider-top\" style=\"color:#fff;\"><\/div><div class=\"swiper\" data-settings='{\"autoplay\":{\"delay\":3000,\"pauseOnMouseEnter\":true,\"disableOnInteraction\":false},\"speed\":700,\"direction\":\"horizontal\",\"autoHeight\":\"\",\"loop\":true,\"centeredSlides\":true,\"spaceBetween\":0,\"slidesPerView\":1,\"slidesPerGroup\":1,\"effect\":\"slide\",\"coverflowEffect\":{\"rotate\":30,\"slideShadows\":false,\"depth\":100,\"stretch\":50,\"modifier\":1},\"fadeEffect\":{\"crossFade\":true},\"zoom\":\"\",\"navigation\":{\"nextEl\":\"#gutenslider-cxx39g3gr .eedee-gutenslider-next\",\"prevEl\":\"#gutenslider-cxx39g3gr .eedee-gutenslider-prev\"},\"pagination\":{\"type\":\"bullets\",\"clickable\":true,\"dynamicBullets\":false,\"el\":\"#gutenslider-cxx39g3gr .eedee-gutenslider-pagination\"},\"pauseOnHover\":\"1\",\"watchSlidesProgress\":true,\"watchSlidesVisibility\":true,\"settingsMd\":{\"autoHeight\":\"\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"settingsLg\":{\"autoHeight\":\"1\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"hasLg\":true,\"hasLgCounter\":true,\"isFullScreen\":false,\"arrowsFollowMouse\":false,\"lgTitle\":\"none\",\"lgCaption\":\"none\",\"lgThumbnails\":true,\"lgZoomEnabled\":false,\"keyboard\":{\"keyboard\":{\"enabled\":true,\"onlyInViewport\":true}},\"hashNavigation\":false,\"dividers\":false}'><div class=\"swiper-wrapper\">\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:192;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"1024\" height=\"656\" class=\"wp-image-5216\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-1024x656.jpg\" alt=\"Pittore romano della fine del XVI secolo\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"D395 CORNICE\" data-title=\"Paesaggio con la preghiera del Beato Isidoro Agricola\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-1024x656.jpg 1024w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-300x192.jpg 300w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-768x492.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-1600x1025.jpg 1600w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-1536x984.jpg 1536w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-2048x1313.jpg 2048w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-228x146.jpg 228w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-50x32.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-117x75.jpg 117w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-960x615.jpg 960w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-749x480.jpg 749w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/d395-con-cornice-copia-480x308.jpg 480w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:158;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"1024\" height=\"539\" class=\"wp-image-5214\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-1024x539.jpg\" alt=\"Pittore romano della fine del XVI secolo\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"D395\" data-title=\"Paesaggio con la preghiera del Beato Isidoro Agricola\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-1024x539.jpg 1024w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-300x158.jpg 300w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-768x404.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-1600x842.jpg 1600w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-1536x809.jpg 1536w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-2048x1078.jpg 2048w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-260x137.jpg 260w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-50x26.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-142x75.jpg 142w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-1630x860.jpg 1630w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-960x505.jpg 960w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-912x480.jpg 912w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2023\/11\/Senza-nome-480x253.jpg 480w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n<\/div><\/div><button class=\"eedee-gutenslider-nav eedee-gutenslider-prev\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"13\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M10.828 12l4.95 4.95-1.414 1.414L8 12l6.364-6.364 1.414 1.414z\"\/><\/svg><\/button><button class=\"eedee-gutenslider-nav eedee-gutenslider-next\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"11\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M13.172 12l-4.95-4.95 1.414-1.414L16 12l-6.364 6.364-1.414-1.414z\"\/><\/svg><\/button><div class=\"eedee-gutenslider-pagination\"><\/div><div class=\"gutenslider-divider-bottom \" style=\"color:#fff;\"><\/div><\/div><\/div>\n\n\n<p class=\"has-text-align-center\">PITTORE ROMANO DELLA FINE DEL XVI SECOLO<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Paesaggio con la preghiera del Beato Isidoro Agricola<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">olio su tela, cm 67&#215;124<\/p>\n\n\n\n<p>Il dipinto raffigura un\u2019intensa e luminosa veduta di paesaggio, sul cui sfondo e nella nebbia si intravede un lago attraversato da una barca e un castello su un piccolo promontorio. La luce colpisce il centro della composizione costruendo cos\u00ec una precisa veduta prospettica, con animali al pascolo e vari personaggi. In primo piano \u00e8 un giovane inginocchiato di fronte ad una fonte che zampilla. Sulla buca del terreno \u00e8 infilata ancora la zappa usata dall\u2019agricoltore per il suo lavoro.<\/p>\n\n\n\n<p>\u00c8 chiaramente un episodio della vita di Sant\u2019Isidoro Agricola, in cui si racconta che durante il lavoro riusc\u00ec miracolosamente a far nascere una fonte con un colpo di zappa. Mentre era intento a pregare il Signore per il prodigio, un angelo prese il suo posto al lavoro e fu visto arare i suoi campi. Testimone fu il padrone del terreno, stupito per l\u2019avvenimento e rappresentato col cappello in testa.<\/p>\n\n\n\n<p>Stilisticamente il paesaggio ricorda da vicino le prove romane di Paul Brill, paesista fiammingo di gran successo presso le corti pontificie tra Gregorio XIII e Sisto V. Non \u00e8 da ritenersi un caso che il luogo in cui venne stampata per la prima volta, nel 1477, la vita di Sant\u2019Isidoro Agricola \u2013 in cui il culto era assai presente \u2013 fosse proprio Ascoli Piceno, citt\u00e0 a cui il papa marchigiano Sisto V era molto legato. Paul Brill partecip\u00f2 ai lavori in Vaticano durante il pontificato di quest\u2019ultimo e proprio questo dipinto potrebbe essere uscito dalla sua bottega alla fine del XVI secolo. Nonostante il culto fosse gi\u00e0 diffuso, Sant\u2019Isidoro fu canonizzato nel 1622 (insieme a San Filippo Neri) e quest\u2019opera precede quella data.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":5214,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-types":[16],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/5213"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=5213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/5214"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=5213"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=5213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}