{"id":2944,"date":"2020-10-17T15:10:41","date_gmt":"2020-10-17T15:10:41","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=2944"},"modified":"2026-07-01T15:31:18","modified_gmt":"2026-07-01T15:31:18","slug":"coppia-di-stemmi","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/coppia-di-stemmi\/","title":{"rendered":"Coppia di stemmi a scudo accartocciato"},"content":{"rendered":"<p style=\"text-align: center;\">ALONSO BERRUGUETE<\/p>\n<p style=\"text-align: center;\">Peredes de Nava 1488-Toledo 1561<\/p>\n<p style=\"text-align: center;\"><em>Coppia di stemmi a scudo accartocciato<\/em><\/p>\n<p style=\"text-align: center;\">legno intagliato, dorato e dipinto, cm 40&#215;18<\/p>\n<p class=\"p1\">I due scudi lignei che qui presentiamo, rivestiti in foglia d\u2019oro, rivelano per qualit\u00e0 dell\u2019intaglio e raffinatezza esecutiva caratteri riconducibili al Rinascimento spagnolo. Le lievi differenze nel taglio indicano una lavorazione a mano libera, priva di disegno preparatorio.<\/p>\n<p class=\"p1\">La tipologia decorativa si inserisce nella tradizione dei riquadri di matrice gotica ancora diffusi tra XV e XVI secolo, particolarmente radicati nel contesto iberico.<\/p>\n<p class=\"p1\">Per caratteristiche formali e stilistiche, i due manufatti possono essere collocati nella prima met\u00e0 del XVI secolo, in un ambito artistico vicino alla scuola di Alonso Berruguete, protagonista del Rinascimento spagnolo e profondamente influenzato dall\u2019esperienza italiana e dall\u2019opera di Michelangelo.<\/p>\n<p class=\"p1\">Elementi analoghi si riscontrano nei <i>retabli<\/i>, imponenti pale d\u2019altare della tradizione iberica, dove scultura e pittura si integrano in complesse strutture lignee dorate. In opere come il Retablo della Mejorada di Olmedo (1526), oggi al Museo Nacional de Escultura di Valladolid, scudi araldici analoghi compaiono alle estremit\u00e0 della predella, con funzione celebrativa della committenza e valore documentario per la datazione e l\u2019attribuzione dell\u2019opera.<\/p>\n<p class=\"p1\">Nel caso in esame, il campo degli scudi presenta due armi gentilizie corredate da ornamenti onorifici \u2013 elmi, cercini e lambrecchini \u2013 che indicano il rango del titolare. La loro sovrapposizione altera le consuete partizioni araldiche, rendendo pi\u00f9 complessa l\u2019identificazione degli stemmi, sebbene le tracce dei quarti permettano ancora di ipotizzarne la lettura originaria.<\/p>\n<p class=\"p1\">La forma degli scudi appartiene alla tipologia detta <i>accartocciata<\/i>, caratterizzata da volute e ricci simili a pergamene arrotolate. Diffusa in Italia nel XVI secolo e poi in tutta Europa, questa foggia rappresenta una delle evoluzioni decorative dello scudo araldico rinascimentale.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2945,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-types":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/2944"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=2944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/2945"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=2944"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=2944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}