{"id":2147,"date":"2019-11-02T16:09:46","date_gmt":"2019-11-02T16:09:46","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=2147"},"modified":"2025-07-18T08:53:46","modified_gmt":"2025-07-18T08:53:46","slug":"coppia-di-tavoli-a-demi-lune-2","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/coppia-di-tavoli-a-demi-lune-2\/","title":{"rendered":"Coppia di consoles a demi-lune"},"content":{"rendered":"\n<p class=\"has-text-align-center\">COPPIA DI CONSOLES A DEMI-LUNE<\/p>\n\n\n\n<p class=\"has-text-align-center\">legno listrato in mogano, piano in scagliola<\/p>\n\n\n\n<p>Queste raffinate consoles a demi-lune, realizzate in legno di mogano, vantano un&#8217;origine riconducibile all&#8217;ambito napoletano. La loro caratteristica pi\u00f9 distintiva \u00e8 senza dubbio il piano superiore semicircolare in scagliola, un&#8217;opera d&#8217;arte in s\u00e9. La decorazione, meticolosamente eseguita, presenta motivi di armi e vessilli che convergono al centro in uno stemma araldico. Questo blasone \u00e8 identificabile con la casata di Carlo I d&#8217;Angi\u00f2 (\u201cD&#8217;azur sem\u00e9 de fleurs de lys d&#8217;or, \u00e0 un lambel de quatre pi\u00e8ces de gueules\u201d), conferendo ai mobili un&#8217;aura storica e nobiliare.<\/p>\n\n\n\n<p>Sotto il piano, una fascia lineare ospita un cassetto centrale, impreziosito da una serratura e una bocchetta in ottone, che ne sottolineano la funzionalit\u00e0 oltre che l&#8217;estetica. Le consoles poggiano su quattro gambe: quelle posteriori, lineari e robuste, sono tipiche dei mobili da parete e garantiscono stabilit\u00e0, mentre quelle anteriori si distinguono per la loro forma curva e intagli elaborati. Questi ultimi, che richiamano motivi a fogliame stilizzato, aggiungono un tocco di squisita raffinatezza, terminando in eleganti zampe caprine.<\/p>\n\n\n\n<p>La base, una pedana concava sui tre lati frontali, \u00e8 sostenuta da piedi a cipolla schiacciata che si concludono con un elemento sferico, completando l&#8217;armonia delle forme.<\/p>\n\n\n\n<p>Basandosi sulle loro caratteristiche distintive \u2013 in particolare la forma a demilune, gli intagli delle gambe, i piedi a zampa e la ricca decorazione del piano \u2013 queste consoles suggeriscono un&#8217;affinit\u00e0 con lo Stile Impero, quest\u2019ultimo fiorito a cavallo tra la fine del XVIII e l&#8217;inizio del XIX secolo e noto per la sua maestosit\u00e0 e l&#8217;ispirazione all&#8217;arte classica.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Napoli, secondo quarto del XIX secolo<\/p>\n\n\n\n<p class=\"has-text-align-center\">cm 100x115x57<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":6697,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[28],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/2147"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=2147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/6697"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=2147"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=2147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}