{"id":1975,"date":"2019-10-28T15:08:56","date_gmt":"2019-10-28T15:08:56","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=1975"},"modified":"2023-09-15T12:40:29","modified_gmt":"2023-09-15T12:40:29","slug":"1975","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/1975\/","title":{"rendered":"Pendola con Cupido e Vestale"},"content":{"rendered":"<p style=\"text-align: center;\">PENDOLA CON CUPIDO E VESTALE<\/p>\n<p style=\"text-align: center;\">bronzo dorato<\/p>\n<p>Questa pendola \u00e8 databile al periodo Impero, periodo nel quale la rigorosa geometria della struttura base, creata dalla cassa posta sopra ad un basamento di maggiori dimensioni \u2013 talvolta in posizione centrata come in questo caso, talvolta posta su un lato \u2013 veniva di volta in volta impreziosita da fantasiose figurazioni, solitamente ispirate dall\u2019inesauribile repertorio mitologico. Il nostro manufatto raffigura una giovane coronata di lauro, probabilmente una vestale, che si accinge a suonare il diaulos, mentre Amore giunge dall\u2019alto impugnando la cetra. Sul lato destro, un arco, una corona d\u2019alloro e una fiaccola sono poste su un\u2019ara a mezza colonna adornata da teste di capro dalle quali pendono festoni, motivo quest\u2019ultimo che ritorna anche sulla base, sorretto da due amorini in volo.<\/p>\n<p>Quadrante segnato \u201cHoriot a Paris\u201d.<\/p>\n<p style=\"text-align: center;\">Francia, inizi del XIX secolo<\/p>\n<p style=\"text-align: center;\">cm 47,5X33<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1976,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/1975"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=1975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/1976"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=1975"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=1975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}