{"id":1740,"date":"2019-10-17T16:03:12","date_gmt":"2019-10-17T16:03:12","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=1740"},"modified":"2026-05-06T14:50:04","modified_gmt":"2026-05-06T14:50:04","slug":"1740","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/1740\/","title":{"rendered":"Paesaggio con Pan e Siringa"},"content":{"rendered":"<div id=\"gutenslider-78bvs5aet\" class=\"wp-block-eedee-block-gutenslider gs-frontend content-change alignnone adaptive-height arrow-style-1 arrow-position-sides arrow-mb-none arrows-lg arrows-md arrows-sm dot-style-1 dots-lg dots-md dots-sm dot-position-bottom is-position-center-center mb-none lg-zoom-icon wrap-auto-height\" data-parallax-direction=\"down\" data-parallax-amount=\"1.3\" data-lg-transition=\"lg-slide\" data-hash=\"\" ><div class=\"eedee-swiper-outer\" style=\"--gutenslider-min-height: 50vh;--gutenslider-arrow-size: 30px;--gutenslider-dot-size: 25px;--gutenslider-arrow-color: #ffffff;--gutenslider-dot-color: #ffffff;--gutenslider-padding-y-mobile: 40px;--gutenslider-padding-x-mobile: 40px;--gutenslider-padding-y-tablet: 40px;--gutenslider-padding-x-tablet: 40px;--gutenslider-padding-y-desktop: 40px;--gutenslider-padding-x-desktop: 40px;--gutenslider-bg-image: url();--gutenslider-min-height-md: 50vh;--gutenslider-min-height-sm: 50vh;--gutenslider-padding-x: 40px;--gutenslider-padding-x-md: 40px;--gutenslider-padding-x-sm: 20px;--gutenslider-padding-y: 40px;--gutenslider-padding-y-md: 40px;--gutenslider-padding-y-sm: 20px;--gutenslider-arrow-size-md: 30px;--gutenslider-arrow-size-sm: 30px;--gutenslider-dot-size-md: 25px;--gutenslider-dot-size-sm: 25px;--gutenslider-arrow-bg-color: transparent;--gutenslider-arrow-hover-color: #eeeeee;--gutenslider-arrow-bg-hover-color: transparent;--gutenslider-arrow-x-offset: 10px;--gutenslider-arrow-x-offset-md: 10px;--gutenslider-arrow-x-offset-sm: 10px;--gutenslider-arrow-y-offset: 0px;--gutenslider-arrow-y-offset-md: 0px;--gutenslider-arrow-y-offset-sm: 0px;--gutenslider-arrow-x-spacing: 0px;--gutenslider-dot-y-offset: 10px;--gutenslider-dot-y-offset-md: 10px;--gutenslider-dot-y-offset-sm: 10px;--gutenslider-margin-x: 0px;--gutenslider-margin-x-md: 0px;--gutenslider-margin-x-sm: 0px;--gutenslider-margin-y: 0px;--gutenslider-margin-y-md: 0px;--gutenslider-margin-y-sm: 0px;--gutenslider-divider-top: 60px;--gutenslider-divider-bottom: 60px;--gutenslider-lightgallery-bg: #ffffff;--gutenslider-lightgallery-font: #000000;--gs-first-pos: 50% 50%;--gs-gap-vertical: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );--gs-gap-horizontal: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );\"><div class=\"gutenslider-divider-top\" style=\"color:#fff;\"><\/div><div class=\"swiper\" data-settings='{\"autoplay\":{\"delay\":3000,\"pauseOnMouseEnter\":true,\"disableOnInteraction\":false},\"speed\":700,\"direction\":\"horizontal\",\"autoHeight\":\"\",\"loop\":true,\"centeredSlides\":true,\"spaceBetween\":0,\"slidesPerView\":1,\"slidesPerGroup\":1,\"effect\":\"slide\",\"coverflowEffect\":{\"rotate\":30,\"slideShadows\":false,\"depth\":100,\"stretch\":50,\"modifier\":1},\"fadeEffect\":{\"crossFade\":true},\"zoom\":\"\",\"navigation\":{\"nextEl\":\"#gutenslider-78bvs5aet .eedee-gutenslider-next\",\"prevEl\":\"#gutenslider-78bvs5aet .eedee-gutenslider-prev\"},\"pagination\":{\"type\":\"bullets\",\"clickable\":true,\"dynamicBullets\":false,\"el\":\"#gutenslider-78bvs5aet .eedee-gutenslider-pagination\"},\"pauseOnHover\":\"1\",\"watchSlidesProgress\":true,\"watchSlidesVisibility\":true,\"settingsMd\":{\"autoHeight\":\"\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"settingsLg\":{\"autoHeight\":\"1\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":true},\"hasLg\":true,\"hasLgCounter\":true,\"isFullScreen\":false,\"arrowsFollowMouse\":false,\"lgTitle\":\"none\",\"lgCaption\":\"none\",\"lgThumbnails\":true,\"lgZoomEnabled\":false,\"keyboard\":{\"keyboard\":{\"enabled\":true,\"onlyInViewport\":true}},\"hashNavigation\":false,\"dividers\":false}'><div class=\"swiper-wrapper\">\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:206;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"1024\" height=\"705\" class=\"wp-image-4599\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-1024x705.jpg\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"d320 con cornice\" data-title=\"Paesaggio con Pan e Siringa\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-1024x705.jpg 1024w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-300x206.jpg 300w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-768x529.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-1600x1101.jpg 1600w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-1536x1057.jpg 1536w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-2048x1410.jpg 2048w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-212x146.jpg 212w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-50x34.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-109x75.jpg 109w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-960x661.jpg 960w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-copia-697x480.jpg 697w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:200;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"1024\" height=\"681\" class=\"wp-image-1741\" src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-1024x681.jpg\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-caption=\"d320\" data-title=\"Paesaggio con Pan e Siringa\" srcset=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-1024x681.jpg 1024w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-300x200.jpg 300w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-768x511.jpg 768w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-220x146.jpg 220w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-50x33.jpg 50w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-113x75.jpg 113w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-960x638.jpg 960w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320-722x480.jpg 722w, https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/d320.jpg 1200w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size\"><\/p>\n\n<\/div><\/div>\n<\/div><\/div><button class=\"eedee-gutenslider-nav eedee-gutenslider-prev\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"13\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M10.828 12l4.95 4.95-1.414 1.414L8 12l6.364-6.364 1.414 1.414z\"\/><\/svg><\/button><button class=\"eedee-gutenslider-nav eedee-gutenslider-next\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"11\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M13.172 12l-4.95-4.95 1.414-1.414L16 12l-6.364 6.364-1.414-1.414z\"\/><\/svg><\/button><div class=\"eedee-gutenslider-pagination\"><\/div><div class=\"gutenslider-divider-bottom \" style=\"color:#fff;\"><\/div><\/div><\/div>\n\n<p style=\"text-align: center;\">PAUL BRIL<\/p>\n<p style=\"text-align: center;\">Anversa, 1554 &#8211; Roma, 1626<\/p>\n<p style=\"text-align: center;\"><em>Paesaggio con Pan e Siringa<\/em><\/p>\n<p style=\"text-align: center;\">olio su tela, cm 49&#215;71<\/p>\n<p><\/p>\n<p>Dinanzi ad un sereno paesaggio, una vallata amena percorsa da un placido fiume, il dio Pan insegue la ninfa Siringa. L&#8217;occhio dell&#8217;osservatore \u00e8 invitato a indagare attentamente la tela, impreziosita con incredibile dovizia di particolari: minuscoli uccelli variopinti, un cavaliere che avanza su un distante sentiero, ville e antichi manieri in lontananza. La luce filtra dalle nuvole illuminando a sprazzi le colline al di l\u00e0 dell&#8217;ombrosa quinta sul proscenio.<\/p>\n<p>Questa visione lenticolare, particolarmente apprezzabile per l&#8217;eccellente stato di conservazione, unita ai caratteristici toni freddi dalla dominante azzurra, sono elementi caratteristici dell&#8217;autore della tela, il fiammingo Paul Bril. Pi\u00f9 precisamente, come segnalatoci da Francesca Cappelletti autrice di una scheda sull&#8217;opera in esame, &#8220;il dipinto, nella sua partizione in una zona a sinistra chiusa dagli alberi intorno a una radura in ombra e in una parte destra che si apre sul paesaggio fluviale e su un sovrapporsi di colline tondeggianti verso l&#8217;orizzonte, \u00e8 tipico della produzione di Paul Bril negli anni Venti del Seicento&#8221;.<\/p>\n<p>Ricordato nella Citt\u00e0 Eterna a partire dalla fine dell&#8217;ottavo decennio del Cinquecento, l&#8217;artista nativo di Anversa divenne il caposcuola della pittura di paesaggio a Roma, citt\u00e0 nella quale godette di grande successo, fino a divenire Principe dell&#8217;Accademia di San Luca nel 1620.<\/p>\n<p>All&#8217;anno che segue l&#8217;importante riconoscimento risalgono entrambi i dipinti, firmati e datati da Bril, indicati dalla Cappelletti come confronti per la nostra tela: il <em>Paesaggio con Cefalo e Procri<\/em> di Palazzo Barberini e il <em>Paesaggio con Guado<\/em> della collezione Denis Mahon. La studiosa evidenzia anche il rapporto con il rame conservato al Louvre dello stesso soggetto della nostra opera, anch&#8217;esso riconducibile al 1620-1621, nel quale le due figure di Pan che insegue Siringa &#8220;sono rappresentate nello stesso atteggiamento ma in controparte rispetto al nostro dipinto&#8221;.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1741,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"portfolio-types":[17,16],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/1740"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=1740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/1741"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=1740"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=1740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}