{"id":1405,"date":"2019-09-16T17:10:37","date_gmt":"2019-09-16T17:10:37","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=1405"},"modified":"2026-06-30T15:00:00","modified_gmt":"2026-06-30T15:00:00","slug":"madonna-dellumilta","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/madonna-dellumilta\/","title":{"rendered":"Madonna dell\u2019Umilt\u00e0"},"content":{"rendered":"<p style=\"text-align: center;\">ZANINO DI PIETRO<\/p>\n<p style=\"text-align: center;\">Documentato a Bologna, 1389 &#8211; Venezia, 1448 circa<\/p>\n<p style=\"text-align: center;\"><em>Madonna dell\u2019Umilt\u00e0<\/em><\/p>\n<p style=\"text-align: center;\">tempera e oro su tavola, cm 50&#215;33<\/p>\n<p class=\"p1\">Alla fine del Trecento Niccol\u00f2 di Pietro recupera a Venezia l\u2019iconografia della Madonna dell\u2019Umilt\u00e0, inaugurata agli inizi del secolo da Simone Martini ad Avignone: la Vergine \u00e8 raffigurata seduta su un prato, talvolta su un cuscino dorato, secondo una tipologia destinata a larga fortuna in ambito lagunare. In questo solco si inserisce la tavola in esame, una graziosa Madonna dell\u2019Umilt\u00e0 oggi riconosciuta come opera di Zanino di Pietro (al secolo Giovanni di Pietro Charlier), tra i pi\u00f9 rappresentativi interpreti della pittura tardogotica veneziana, attivo in laguna per tutta la prima met\u00e0 del XV secolo. Le vicende note del dipinto iniziano tuttavia soltanto negli anni Settanta del Novecento, con due passaggi sul mercato antiquario, dapprima con attribuzione alla scuola di Gentile da Fabriano, quindi, successivamente, come scuola di Jacobello del Fiore. L\u2019assegnazione a Zanino, rimasta a lungo ai margini della letteratura, \u00e8 stata correttamente proposta da Angelelli (in Pittura dal Duecento, 1991), da Filippo Todini, sulla base della fotografia conservata presso il Kunsthistorisches Institut di Firenze (inv. 451354, come Giovanni di Francia), e, pi\u00f9 recentemente, ribadita da Linda Pisani. Valentina Baradel inserisce il dipinto nel catalogo della sua monografia sul pittore del 2019. La questione cronologica appare centrale. Se Pisani proponeva una datazione nel secondo decennio del secolo, collocando l\u2019opera nella fase veneziana matura del pittore e mettendola in relazione con la Madonna della Galleria Nazionale di Atene e con quella oggi presso la Collezione Fioratti di New York, un\u2019anticipazione al primo decennio, gi\u00e0 suggerita da Angelelli, e ribadita da Baradel, sembra tuttavia pi\u00f9 convincente, soprattutto nelle incertezze nel trattamento dello scorcio, e nel rapporto stretto con la prima fase veneziana di Gentile da Fabriano. Analogamente, la ripresa speculare del braccio del Bambino appoggiato alla gambina, gi\u00e0 sperimentata nella cosiddetta Madonna degli Alberetti (Collezione Bianchi Bonomi, Milano), orienta la nostra opera verso una fase precoce, probabilmente a ridosso del rientro dell\u2019artista in laguna dopo l\u2019esperienza maturata verosimilmente in ambito bolognese, che contribuisce a spiegare il progressivo \u201cingentilimento\u201d del linguaggio di Zanino, pienamente visibile nel volto della Vergine. Questo segna un avanzamento rispetto a prove precedenti, pur mantenendo una tensione ancora sperimentale. Particolarmente significativa \u00e8 la lavorazione dell\u2019oro: dalla fitta razzatura di fondo alle decorazioni dei nimbi, ornati con punzoni ad anello a due circoli disposti a losanga, rosette concentriche e lettere granite, in diretta ripresa dalla coeva produzione di Gentile. Nella passamaneria del manto compare infine un ornato a spirale inciso con stilo appuntito, in linea con la tradizione veneziana del Trecento, gi\u00e0 sperimentato dall\u2019artista in altre opere.<\/p>\n<p>Pubblicazioni:<\/p>\n<p class=\"p1\">\u201cCatalogo Fototeca Kunstihistorisches Institut di Firenze\u201d, scheda n. KHI 451354.<\/p>\n<p>\u201cPittura dal Duecento al primo Cinquecento nelle fotografie di Girolamo Bombelli&#8221;, a cura di A. G. De Marchi, Electa Mondadori, Milano, 1991, cat. 585, p. 237.<\/p>\n<p class=\"p1\">\u201cZanino di Pietro. Un protagonista della pittura veneziana fra Tre e Quattrocento\u201d, a cura di Valentina Baradel, Poligrafo, Padova, 2019, pp. 179-180, fig. XIV, scheda 7.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1406,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[15],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/1405"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=1405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/1406"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=1405"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}