{"id":1332,"date":"2019-09-13T16:14:12","date_gmt":"2019-09-13T16:14:12","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=1332"},"modified":"2023-09-21T09:07:06","modified_gmt":"2023-09-21T09:07:06","slug":"madonna-con-il-bambino-2","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/madonna-con-il-bambino-2\/","title":{"rendered":"Pace con Madonna col Bambino"},"content":{"rendered":"<p style=\"text-align: center;\">IL MODERNO (GALEAZZO MONDELLA)<\/p>\n<p style=\"text-align: center;\">attivo in Lombardia e a Roma tra XV e XVI secolo<\/p>\n<p style=\"text-align: center;\"><em>Pace con Madonna col Bambino<\/em><\/p>\n<p style=\"text-align: center;\">argento, cm 11&#215;7<\/p>\n<p>Questo delizioso rilievo in argento di ridotte dimensioni assolse in passato la funzione di pace, oggetto liturgico fatto baciare ai fedeli durante la comunione. Vi \u00e8 raffigurata la Madonna seduta con il Bambino in collo, in una posa apparentemente derivata da idee raffaellesche, espresse in opere quali la Madonna Bridgewater del 1508 (Edimburgo, National Gallery of Scotland). Completano l\u2019immagine San Giuseppe, con in mano una piccola croce, e altre figure incise con estrema finezza sullo sfondo, riconoscibili in santi e angeli.<\/p>\n<p>La rappresentazione \u00e8 contenuta all\u2019interno di un\u2019edicola rinascimentale riccamente ornata con motivi geometrici e a palmette. Nella parte alta il timpano \u00e8 impreziosito dall\u2019immagine di Dio padre e un cherubino, mentre la predella \u00e8 centrata da uno scudo contenente l\u2019arme medicea.<\/p>\n<p>Questa iconografia \u00e8 opera del celebre medaglista e orefice noto come Moderno, attivo in Italia settentrionale a cavallo tra Quattro e Cinquecento, identificato da alcuni nel veronese Galeazzo Mondella (1467-1528). Riconducibile al primo, secondo decennio del Cinquecento, questa immagine \u00e8 nota in ulteriori versioni, quali l\u2019esemplare pressoch\u00e9 identico del Cleveland Museum of Art (inv. 1989.251), leggermente semplificato in certi dettagli e in parte dorato.<\/p>\n<p>Rilievi maggiormente variati in bronzo e bronzo dorato sono presenti nelle collezioni sempre del Metropolitan Museum di New York (inv. 1986.319.24 e 08.189.2) e del Victoria and Albert Museum di Londra (inv. 6977.1860), esemplari nei quali l\u2019arme medicea risulta assente.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1333,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/1332"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=1332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/1333"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=1332"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=1332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}