{"id":1307,"date":"2019-09-13T16:01:37","date_gmt":"2019-09-13T16:01:37","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?post_type=portfolio&#038;p=1307"},"modified":"2026-07-01T15:27:09","modified_gmt":"2026-07-01T15:27:09","slug":"1307","status":"publish","type":"portfolio","link":"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/1307\/","title":{"rendered":"Croce da tavolo"},"content":{"rendered":"<p style=\"text-align: center;\">CROCE DA TAVOLO<\/p>\n<p style=\"text-align: center;\">legno di ebano, intarsi in pietre dure con parti in bronzo dorato<\/p>\n<p class=\"p1\">Il crocifisso d\u2019altare raffigurato \u00e8 un importante arredo liturgico di manifattura fiorentina databile agli inizi del XVII secolo, realizzato con una raffinata combinazione di materiali preziosi e impreziosito da intarsi in pietre dure. Al centro della composizione si trova la figura di Cristo crocifisso, modellata in bronzo dorato con proporzioni eleganti e slanciate: il capo reclinato e il perizoma mosso da leggere pieghe rimandano a una tipologia iconografica diffusa nell\u2019arte sacra tra Rinascimento e primo Barocco.<\/p>\n<p class=\"p1\">L\u2019opera si compone di una base architettonica articolata, concepita come un piccolo altare in miniatura. Il corpo centrale, sormontato da un timpano e raccordato agli elementi laterali pi\u00f9 bassi tramite volute, sostiene la croce vera e propria. La struttura \u00e8 arricchita da pannelli in pietre dure incastonate e da numerosi elementi ornamentali in bronzo dorato, tra cui una Veronica con l\u2019effigie del volto di Cristo, la colomba dello Spirito Santo e testine di leoni all\u2019antica.<\/p>\n<p class=\"p1\">La croce, realizzata in legno ebanizzato e impreziosita da inserti di pietre dure disposte lungo i bracci e il montante verticale, presenta eleganti terminazioni dorate di gusto manierista, decorate con teste di cherubini. Sopra il capo di Cristo \u00e8 collocato il tradizionale cartiglio con la scritta INRI nelle tre lingue canoniche \u2014 ebraico, greco e latino \u2014 mentre sotto i piedi compare un piccolo teschio, simbolo del Golgota e della redenzione attraverso la croce.<\/p>\n<p class=\"p1\">Il Cristo crocifisso \u00e8 compianto da figure a tutto tondo in bronzo dorato raffiguranti la Vergine Maria e San Giovanni Evangelista, tradizionalmente presenti ai piedi della croce nella scena della crocifissione, affiancati da una coppia di angeli inginocchiati.<\/p>\n<p style=\"text-align: center;\">Firenze, inizi del XVII secolo<\/p>\n<p style=\"text-align: center;\">cm 107 altezza<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1308,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[14],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio\/1307"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=1307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media\/1308"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=1307"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/portfolio-types?post=1307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}