{"id":45,"date":"2018-12-01T10:39:08","date_gmt":"2018-12-01T10:39:08","guid":{"rendered":"https:\/\/antico.tornabuoniarte.it\/?page_id=45"},"modified":"2026-07-02T14:23:59","modified_gmt":"2026-07-02T14:23:59","slug":"tornabuoni-arte-antico","status":"publish","type":"page","link":"https:\/\/antico.tornabuoniarte.it\/it\/","title":{"rendered":"Tornabuoni Arte &#8211; Antico"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content&#8221; el_class=&#8221;barra-pulsanti&#8221;][vc_column css_animation=&#8221;none&#8221; width=&#8221;1\/4&#8243; preset=&#8221;mpc_preset_22&#8243; content_preset=&#8221;_mpc_preset_22&#8243; animation_in_type=&#8221;transition.slideLeftIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;300&#8243; animation_in_delay=&#8221;300&#8243; css=&#8221;.vc_custom_1572362159308{margin-top: 0px !important;border-right-width: 1px !important;padding-top: 0px !important;padding-bottom: 18px !important;background-image: url(https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/Button-Dipinti.jpg?id=2032) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;border-right-color: #636363 !important;border-right-style: solid !important;}&#8221;][vc_tta_accordion shape=&#8221;square&#8221; color=&#8221;chino&#8221; c_align=&#8221;center&#8221; c_icon=&#8221;&#8221; active_section=&#8221;&#8221; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221; el_class=&#8221;tab-categorie&#8221; css=&#8221;.vc_custom_1647270760856{margin-top: 18px !important;}&#8221;][vc_tta_section title=&#8221;Dipinti&#8221; tab_id=&#8221;1572347938840-2c90830d-0646&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/fondi-oro\/\">Fondi Oro<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/rinascimento-e-maniera\/\">Rinascimento e Maniera<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/barocco\/\">Barocco<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/neoclassico-e-ottocento\/\">Neoclassico e Ottocento<\/a><\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][vc_column css_animation=&#8221;none&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.slideLeftIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;300&#8243; animation_in_delay=&#8221;500&#8243; css=&#8221;.vc_custom_1572362165081{margin-top: 0px !important;border-right-width: 1px !important;padding-top: 0px !important;padding-bottom: 18px !important;background-image: url(https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/Button-Mobili.jpg?id=2034) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;border-right-color: #636363 !important;border-right-style: solid !important;}&#8221;][vc_tta_accordion color=&#8221;chino&#8221; c_align=&#8221;center&#8221; c_icon=&#8221;&#8221; active_section=&#8221;&#8221; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221; el_class=&#8221;tab-categorie&#8221; css=&#8221;.vc_custom_1647270868378{margin-top: 18px !important;}&#8221;][vc_tta_section title=&#8221;Mobili&#8221; tab_id=&#8221;1572349240924-c5a5ca29-497s&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/armadi\/\">Armadi<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/cassettoni\/\">Cassettoni<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/cassoni-e-cassapanche\/\">Cassoni e Cassapanche<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/credenze\/\">Credenze<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/librerie\/\">Librerie<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/sedie\/\">Sedute<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/tavoli\/\">Tavoli<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/altro\/\">Altro<\/a><\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][vc_column css_animation=&#8221;none&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.slideLeftIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;300&#8243; animation_in_delay=&#8221;700&#8243; css=&#8221;.vc_custom_1572362170992{margin-top: 0px !important;border-right-width: 1px !important;padding-top: 0px !important;padding-bottom: 18px !important;background-image: url(https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/Button-Sculture.jpg?id=2036) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;border-right-color: #636363 !important;border-right-style: solid !important;}&#8221;][vc_tta_accordion color=&#8221;chino&#8221; c_align=&#8221;center&#8221; c_icon=&#8221;&#8221; active_section=&#8221;&#8221; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221; el_class=&#8221;tab-categorie&#8221; css=&#8221;.vc_custom_1647271278893{margin-top: 18px !important;}&#8221;][vc_tta_section title=&#8221;Sculture&#8221; tab_id=&#8221;1572349246859-8c26fdf1-eb4h&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/medioevo\/\">Medioevo<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/rinascimento-e-maniera-s\/\">Rinascimento e Maniera<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/barocco-s\/\">Barocco<\/a> <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/neoclassico-e-ottocento-s\/\">Neoclassico e Ottocento<\/a><\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][vc_column css_animation=&#8221;none&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.slideLeftIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;300&#8243; animation_in_delay=&#8221;900&#8243; css=&#8221;.vc_custom_1572362178772{margin-top: 0px !important;padding-top: 0px !important;padding-bottom: 18px !important;background-image: url(https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2019\/10\/Button-Oggetti.jpg?id=2030) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_tta_accordion color=&#8221;chino&#8221; c_align=&#8221;center&#8221; c_icon=&#8221;&#8221; active_section=&#8221;&#8221; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221; el_class=&#8221;tab-categorie&#8221; css=&#8221;.vc_custom_1647271284158{margin-top: 18px !important;}&#8221;][vc_tta_section title=&#8221;Oggetti&#8221; tab_id=&#8221;1572349250871-30f08be9-11cv&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tipologia-collezioni\/oggetti\/\">Oggetti<\/a><\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1647269942255{padding-top: 6em !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;5294&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; css=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1543922769576{margin-top: 5em !important;margin-bottom: 5em !important;}&#8221;]<div id=\"mpc_dropcap-86a577d89654c7\" class=\"mpc-dropcap mpc-init \">T<\/div>[vc_column_text css=&#8221;&#8221;]<strong>ornabuoni Arte<\/strong> amplia la propria consolidata esperienza nel mercato dell\u2019arte \u2014 gi\u00e0 affermata attraverso le gallerie dedicate all\u2019arte moderna e contemporanea \u2014 al raffinato universo dei dipinti, delle sculture e degli arredi antichi, dal Medioevo al XIX secolo.<\/p>\n<p data-start=\"282\" data-end=\"636\">La sede principale della galleria si trova al piano terra di Palazzo Giovanni, prestigioso edificio trecentesco situato in Via Maggio, nel cuore di Firenze, a pochi passi da Palazzo Pitti. Dal 2024, la galleria ha ulteriormente ampliato i propri spazi espositivi con l\u2019inaugurazione di una nuova sede all\u2019interno dello storico Palazzo di Bianca Cappello.<\/p>\n<p data-start=\"638\" data-end=\"928\" data-is-last-node=\"\" data-is-only-node=\"\">La collezione, ampia e accuratamente selezionata, dedica particolare attenzione ai grandi maestri del <strong>Rinascimento<\/strong> e del <strong>Barocco<\/strong>. Comprende inoltre preziosi \u201c<strong>fondi oro<\/strong>\u201d del XIV e XV secolo, raccolti in una saletta dedicata che richiama l\u2019atmosfera suggestiva delle antiche chiese medievali.<\/p>\n<p>[\/vc_column_text]<a href=\"https:\/\/antico.tornabuoniarte.it\/it\/chi-siamo\/\" title=\"Link\"  data-id=\"mpc_button-736a577d8965549\" class=\"mpc-button mpc-init mpc-transition mpc-typography--mpc_preset_20 \" ><div class=\"mpc-button__content mpc-effect-type--stay mpc-effect-side--left\"><i class=\"mpc-button__icon mpc-transition  fa fa-paper-plane\"><\/i><span class=\"mpc-button__title mpc-transition\">Leggi di pi\u00f9...<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--slide mpc-effect-side--left\"><\/div><\/a>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1553340893078{background-color: #f4f4f4 !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_empty_space height=&#8221;55px&#8221; css=&#8221;.vc_custom_1543921065477{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1778595883640{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;]<\/p>\n<h2>In evidenza<\/h2>\n<p>[\/vc_column_text][vc_separator color=&#8221;orange&#8221; css=&#8221;.vc_custom_1543918091193{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;][vc_column_text css=&#8221;&#8221;]<\/p>\n<div class=\"get_in_touch_wrapper\">Una selezione di opere in rilievo<\/div>\n<p>[\/vc_column_text]<a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/\" title=\"Link\"  data-id=\"mpc_button-456a577d89655c1\" class=\"mpc-button mpc-init mpc-transition mpc-typography--mpc_preset_20 \" ><div class=\"mpc-button__content mpc-effect-type--stay mpc-effect-side--left\"><i class=\"mpc-button__icon mpc-transition  fa fa-bookmark\"><\/i><span class=\"mpc-button__title mpc-transition\">Guarda la collezione...<\/span><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--slide mpc-effect-side--left\"><\/div><\/a>[vc_empty_space height=&#8221;55&#8243; css=&#8221;.vc_custom_1543921070256{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_empty_space height=&#8221;55px&#8221; css=&#8221;.vc_custom_1543921065477{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;]<div class=\"mpc-carousel__wrapper mpc-waypoint\"><div id=\"mpc_carousel_posts-786a577d8966c91\" class=\"mpc-carousel-posts mpc-init mpc-init mpc-transition mpc-overlay--slide-down mpc-item--slide-up mpc-layout--style_1 carosello-home carosello-home\"   data-mpcslick='{\"infinite\":true,\"autoplay\":true,\"slidesToShow\":4,\"slidesToScroll\":1,\"centerMode\":false,\"initialSlide\":0,\"autoplaySpeed\":1500}' data-slick-cols=\"4\"><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-7-8-1024x832.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/venere-e-amorini\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/venere-e-amorini\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/venere-e-amorini\/\" title=\"Read more about Venere e amorini\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-7-8-scaled.jpg\" title=\"Venere e amorini\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/venere-e-amorini\/\" title=\"Venere e amorini\">Venere e amorini<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/venere-e-amorini\/\" title=\"Venere e amorini\">Venere e amorini<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-7-6-793x1024.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/ritratto-di-giovane\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/ritratto-di-giovane\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/ritratto-di-giovane\/\" title=\"Read more about Ritratto di giovane\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/07\/Senza-nome-7-6-scaled.jpg\" title=\"Ritratto di giovane\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/ritratto-di-giovane\/\" title=\"Ritratto di giovane\">Ritratto di giovane<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/ritratto-di-giovane\/\" title=\"Ritratto di giovane\">Ritratto di giovane<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/Senza-nome-3-1024x732.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/diana-al-bagno-e-atteone\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/diana-al-bagno-e-atteone\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/diana-al-bagno-e-atteone\/\" title=\"Read more about Diana al bagno e Atteone\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/Senza-nome-3-scaled.jpg\" title=\"Diana al bagno e Atteone\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/diana-al-bagno-e-atteone\/\" title=\"Diana al bagno e Atteone\">Diana al bagno e Atteone<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/diana-al-bagno-e-atteone\/\" title=\"Diana al bagno e Atteone\">Diana al bagno e Atteone<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/d495-1024x768.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/veduta-di-venezia-con-chiesa-di-santa-maria-della-carita\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/veduta-di-venezia-con-chiesa-di-santa-maria-della-carita\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/veduta-di-venezia-con-chiesa-di-santa-maria-della-carita\/\" title=\"Read more about Veduta di Venezia con Chiesa di Santa Maria della Carit\u00e0\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/d495-scaled.jpg\" title=\"Veduta di Venezia con Chiesa di Santa Maria della Carit\u00e0\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/veduta-di-venezia-con-chiesa-di-santa-maria-della-carita\/\" title=\"Veduta di Venezia con Chiesa di Santa Maria della Carit\u00e0\">Veduta di Venezia con Chiesa di Santa Maria della Carit\u00e0<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/veduta-di-venezia-con-chiesa-di-santa-maria-della-carita\/\" title=\"Veduta di Venezia con Chiesa di Santa Maria della Carit\u00e0\">Veduta di Venezia con Chiesa di Santa Maria della Carit\u00e0<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/d493-1024x768.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-lacustre\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-lacustre\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-lacustre\/\" title=\"Read more about Paesaggio lacustre\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/d493-scaled.jpg\" title=\"Paesaggio lacustre\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-lacustre\/\" title=\"Paesaggio lacustre\">Paesaggio lacustre<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-lacustre\/\" title=\"Paesaggio lacustre\">Paesaggio lacustre<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/d494-1024x768.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-campestre\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-campestre\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-campestre\/\" title=\"Read more about Paesaggio campestre\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/06\/d494-scaled.jpg\" title=\"Paesaggio campestre\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-campestre\/\" title=\"Paesaggio campestre\">Paesaggio campestre<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-typography--preset_2 mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/collezioni\/paesaggio-campestre\/\" title=\"Paesaggio campestre\">Paesaggio campestre<\/a><\/h3><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--left mpc-navigation--style_5 mpc-on-hover  mpc-nav-preset--mpc_preset_28\" data-mpcslider=\"mpc_carousel_posts-786a577d8966c91\"><div class=\"mpc-nav__arrow mpcslick-prev\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_carrot-left\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--slide mpc-effect-side--bottom\"><\/div><\/i><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--left mpc-navigation--style_5 mpc-on-hover  mpc-nav-preset--mpc_preset_28\" data-mpcslider=\"mpc_carousel_posts-786a577d8966c91\"><div class=\"mpc-nav__arrow mpcslick-next\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_carrot-right\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--slide mpc-effect-side--bottom\"><\/div><\/i><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; gap=&#8221;30&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; css=&#8221;.vc_custom_1612015176507{margin-top: 50px !important;margin-bottom: 0px !important;}&#8221;][vc_column width=&#8221;2\/3&#8243; preset=&#8221;mpc_preset_75&#8243; content_preset=&#8221;_mpc_preset_75&#8243; css=&#8221;.vc_custom_1543921110544{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_empty_space height=&#8221;55px&#8221; css=&#8221;.vc_custom_1543921065477{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1778595781984{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;]<\/p>\n<h2>News<\/h2>\n<p>[\/vc_column_text][vc_separator color=&#8221;orange&#8221; css=&#8221;.vc_custom_1543918091193{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;][vc_column_text]<\/p>\n<div class=\"get_in_touch_wrapper\">Contributi editoriali, eventi, informazioni di servizio. <a href=\"https:\/\/antico.tornabuoniarte.it\/it\/news\/\">Leggile tutte&#8230;<\/a><\/div>\n<p>[\/vc_column_text]<div class=\"mpc-carousel__wrapper mpc-waypoint\"><div id=\"mpc_carousel_posts-226a577d896e18a\" class=\"mpc-carousel-posts mpc-init mpc-init mpc-transition mpc-overlay--slide-left mpc-item--fade mpc-layout--style_1  \"   data-mpcslick='{\"infinite\":true,\"autoplay\":false,\"slidesToShow\":2,\"slidesToScroll\":1,\"centerMode\":false,\"initialSlide\":0}' data-slick-cols=\"2\"><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-17-alle-15.38.08-831x1024.png\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/tornabuoni-arte-arte-antica-partecipa-a-amab-2026-bastia-umbra\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/tornabuoni-arte-arte-antica-partecipa-a-amab-2026-bastia-umbra\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tornabuoni-arte-arte-antica-partecipa-a-amab-2026-bastia-umbra\/\" title=\"Read more about Tornabuoni Arte &#8211; Arte Antica partecipa a AMAB 2026, Bastia Umbra\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-17-alle-15.38.08.png\" title=\"Tornabuoni Arte &#8211; Arte Antica partecipa a AMAB 2026, Bastia Umbra\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tornabuoni-arte-arte-antica-partecipa-a-amab-2026-bastia-umbra\/\" title=\"Tornabuoni Arte &#8211; Arte Antica partecipa a AMAB 2026, Bastia Umbra\">Tornabuoni Arte &#8211; Arte Antica partecipa a AMAB 2026, Bastia Umbra<\/a><\/h3><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/tornabuoni-arte-arte-antica-partecipa-a-amab-2026-bastia-umbra\/\" title=\"Tornabuoni Arte &#8211; Arte Antica partecipa a AMAB 2026, Bastia Umbra\">Tornabuoni Arte &#8211; Arte Antica partecipa a AMAB 2026, Bastia Umbra<\/a><\/h3><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/01\/Logo_Modenantiquaria_2026-nero-1.png\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/modenantiquaria-2026\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/modenantiquaria-2026\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/modenantiquaria-2026\/\" title=\"Read more about MODENANTIQUARIA\u00a02026\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/01\/Logo_Modenantiquaria_2026-nero-1.png\" title=\"MODENANTIQUARIA\u00a02026\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/modenantiquaria-2026\/\" title=\"MODENANTIQUARIA\u00a02026\">MODENANTIQUARIA\u00a02026<\/a><\/h3><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/modenantiquaria-2026\/\" title=\"MODENANTIQUARIA\u00a02026\">MODENANTIQUARIA\u00a02026<\/a><\/h3><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d292-607x1024.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/buone-feste-da-tornabuoni-arte-antica\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/buone-feste-da-tornabuoni-arte-antica\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/buone-feste-da-tornabuoni-arte-antica\/\" title=\"Read more about Buone Feste da Tornabuoni Arte Antica!\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2025\/12\/d292.jpg\" title=\"Buone Feste da Tornabuoni Arte Antica!\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/buone-feste-da-tornabuoni-arte-antica\/\" title=\"Buone Feste da Tornabuoni Arte Antica!\">Buone Feste da Tornabuoni Arte Antica!<\/a><\/h3><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/buone-feste-da-tornabuoni-arte-antica\/\" title=\"Buone Feste da Tornabuoni Arte Antica!\">Buone Feste da Tornabuoni Arte Antica!<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--left mpc-navigation--style_1  mpc-nav-preset--\" data-mpcslider=\"mpc_carousel_posts-226a577d896e18a\"><div class=\"mpc-nav__arrow mpcslick-prev\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\"\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/i><\/div><\/div><div class=\"mpc-nav__arrow mpcslick-next\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\"\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/i><\/div><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;55px&#8221; css=&#8221;.vc_custom_1543921065477{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1778595793877{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;]<\/p>\n<h2><span style=\"color: #808080;\"><span style=\"color: #000000;\">V<\/span><\/span>ideo<\/h2>\n<p>[\/vc_column_text][vc_separator color=&#8221;orange&#8221; css=&#8221;.vc_custom_1543918091193{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;][vc_column_text]<\/p>\n<div class=\"get_in_touch_wrapper\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/category\/video\/\">Vai alla sezione con tutti i nostri video.<\/a><\/div>\n<p>[\/vc_column_text]<div class=\"mpc-carousel__wrapper mpc-waypoint\"><div id=\"mpc_carousel_posts-46a577d89725f1\" class=\"mpc-carousel-posts mpc-init mpc-init mpc-transition mpc-overlay--slide-left mpc-item--fade mpc-layout--style_1  \"   data-mpcslick='{\"infinite\":true,\"autoplay\":true,\"slidesToShow\":1,\"slidesToScroll\":1,\"centerMode\":false,\"initialSlide\":0,\"autoplaySpeed\":4000}' data-slick-cols=\"1\"><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2021\/01\/Video-Button-1-copia-2.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/masterpieces-in-dialogue-madonna-in-trono-col-bambino-e-lucio-fontana-oltre-il-tempo-oltre-lo-spazio\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/masterpieces-in-dialogue-madonna-in-trono-col-bambino-e-lucio-fontana-oltre-il-tempo-oltre-lo-spazio\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/masterpieces-in-dialogue-madonna-in-trono-col-bambino-e-lucio-fontana-oltre-il-tempo-oltre-lo-spazio\/\" title=\"Read more about Masterpieces in Dialogue | Madonna in trono col Bambino e Lucio Fontana &#8211; Oltre il tempo, oltre lo spazio\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2021\/01\/Video-Button-1-copia-2.jpg\" title=\"Masterpieces in Dialogue | Madonna in trono col Bambino e Lucio Fontana &#8211; Oltre il tempo, oltre lo spazio\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/masterpieces-in-dialogue-madonna-in-trono-col-bambino-e-lucio-fontana-oltre-il-tempo-oltre-lo-spazio\/\" title=\"Masterpieces in Dialogue | Madonna in trono col Bambino e Lucio Fontana &#8211; Oltre il tempo, oltre lo spazio\">Masterpieces in Dialogue | Madonna in trono col Bambino e Lucio Fontana &#8211; Oltre il tempo, oltre lo spazio<\/a><\/h3><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/masterpieces-in-dialogue-madonna-in-trono-col-bambino-e-lucio-fontana-oltre-il-tempo-oltre-lo-spazio\/\" title=\"Masterpieces in Dialogue | Madonna in trono col Bambino e Lucio Fontana &#8211; Oltre il tempo, oltre lo spazio\">Masterpieces in Dialogue | Madonna in trono col Bambino e Lucio Fontana &#8211; Oltre il tempo, oltre lo spazio<\/a><\/h3><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2021\/01\/Video-Button-1-copia.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/arts-in-dialogue-luca-giordano-gerusalemme-liberata-e-il-compositore-domenico-mazzocchi\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/arts-in-dialogue-luca-giordano-gerusalemme-liberata-e-il-compositore-domenico-mazzocchi\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/arts-in-dialogue-luca-giordano-gerusalemme-liberata-e-il-compositore-domenico-mazzocchi\/\" title=\"Read more about Arts in Dialogue | Luca Giordano, &#8220;Gerusalemme Liberata&#8221; e il compositore Domenico Mazzocchi\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2021\/01\/Video-Button-1-copia.jpg\" title=\"Arts in Dialogue | Luca Giordano, &#8220;Gerusalemme Liberata&#8221; e il compositore Domenico Mazzocchi\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/arts-in-dialogue-luca-giordano-gerusalemme-liberata-e-il-compositore-domenico-mazzocchi\/\" title=\"Arts in Dialogue | Luca Giordano, &#8220;Gerusalemme Liberata&#8221; e il compositore Domenico Mazzocchi\">Arts in Dialogue | Luca Giordano, &#8220;Gerusalemme Liberata&#8221; e il compositore Domenico Mazzocchi<\/a><\/h3><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/arts-in-dialogue-luca-giordano-gerusalemme-liberata-e-il-compositore-domenico-mazzocchi\/\" title=\"Arts in Dialogue | Luca Giordano, &#8220;Gerusalemme Liberata&#8221; e il compositore Domenico Mazzocchi\">Arts in Dialogue | Luca Giordano, &#8220;Gerusalemme Liberata&#8221; e il compositore Domenico Mazzocchi<\/a><\/h3><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2021\/01\/Video-Button-1-copia-2-1.jpg\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/lucio-fontana\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/antico.tornabuoniarte.it\/it\/lucio-fontana\/\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/lucio-fontana\/\" title=\"Read more about Masterpieces in Dialogue | Maestro GM e Giorgio de Chirico\" class=\"mpc-icon-anchor\"><i class=\"mpc-post-overlay__icon mpc-type--readmore etl etl-attachment\"><\/i><\/a><a href=\"https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2021\/01\/Video-Button-1-copia-2-1.jpg\" title=\"Masterpieces in Dialogue | Maestro GM e Giorgio de Chirico\" class=\"mpc-lightbox mpc-icon-anchor mpc-magnific-popup\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox etl etl-magnifying-glass mpc-icon--mirror\"><\/i><\/a><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/lucio-fontana\/\" title=\"Masterpieces in Dialogue | Maestro GM e Giorgio de Chirico\">Masterpieces in Dialogue | Maestro GM e Giorgio de Chirico<\/a><\/h3><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition mpc-text-overflow\"><a href=\"https:\/\/antico.tornabuoniarte.it\/it\/lucio-fontana\/\" title=\"Masterpieces in Dialogue | Maestro GM e Giorgio de Chirico\">Masterpieces in Dialogue | Maestro GM e Giorgio de Chirico<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--left mpc-navigation--style_1  mpc-nav-preset--\" data-mpcslider=\"mpc_carousel_posts-46a577d89725f1\"><div class=\"mpc-nav__arrow mpcslick-prev\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\"\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/i><\/div><\/div><div class=\"mpc-nav__arrow mpcslick-next\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\"\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/i><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1553340869372{margin-top: 50px !important;margin-bottom: 0px !important;padding-bottom: 0px !important;background: #e8e8e8 url(https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2018\/12\/Eventi-blocco-2.jpg?id=686) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1778078167500{padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;padding-left: 0px !important;background-image: url(https:\/\/antico.tornabuoniarte.it\/wp-content\/uploads\/2026\/05\/Allestimento-1-Amart-2025-4-copia.jpeg?id=7157) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_empty_space height=&#8221;500px&#8221; css=&#8221;.vc_custom_1569770194989{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1544094059415{padding-left: 60px !important;}&#8221;][vc_empty_space height=&#8221;55px&#8221; css=&#8221;.vc_custom_1543921065477{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1741088646395{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;]<\/p>\n<h2><span style=\"color: #808080;\"><em>Prossima <\/em><\/span>fiera<\/h2>\n<p>[\/vc_column_text][vc_separator color=&#8221;orange&#8221; css=&#8221;.vc_custom_1543918091193{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;][vc_empty_space height=&#8221;55&#8243; css=&#8221;.vc_custom_1543921070256{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2 style=\"text-align: center;\"><strong>AMART 2026<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>Museo della Permanente | Milano<\/strong><\/p>\n<p style=\"text-align: center;\">4 &#8211; 8 Novembre 2026<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.amart-milano.com\/\" target=\"_blank\" rel=\"noopener\">www.amart-milano.com<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;newsletter-block&#8221; css=&#8221;.vc_custom_1662630919074{margin-top: 75px !important;}&#8221;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;]<div data-id=\"mpc_divider-116a577d897463a\" class=\"mpc-divider-wrap\"><div class=\"mpc-divider mpc-init mpc-align--center \" ><div class=\"mpc-divider__line mpc-side--left\"><span><\/span><span><\/span><span><\/span><\/div><div class=\"mpc-divider__separator\"><div class=\"mpc-divider__content mpc-typography--mpc_preset_1\">NEWSLETTER<\/div><\/div><div class=\"mpc-divider__line mpc-side--right\"><span><\/span><span><\/span><span><\/span><\/div><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\">Iscriviti per ricevere aggiornamenti sulla galleria e le sue attivit\u00e0 \/ unisciti alla nostra mailing list<\/p>\n<p>[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4388-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/45#wpcf7-f4388-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"4388\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4388-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"newsletter\">\n\t<div class=\"nome\">\n\t\t<p><label> Nome<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"cognome\">\n\t\t<p><label> Cognome<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"email\">\n\t\t<p><label> La tua email<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"consenso\">\n\t\t<p><label>Accetta consenso:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ConsensoPrivacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"ConsensoPrivacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Tornabuoni arte utilizzer\u00e0 i tuoi dati personali per tenerti informato e segnalarti iniziative ed eventi culturali legati alle gallerie.<\/span><\/label><\/span><\/span><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"invio\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Iscrivimi\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/pages\/45"}],"collection":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":323,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/pages\/45\/revisions"}],"predecessor-version":[{"id":7349,"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/pages\/45\/revisions\/7349"}],"wp:attachment":[{"href":"https:\/\/antico.tornabuoniarte.it\/it\/wp-json\/wp\/v2\/media?parent=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}